{"id":360,"count":5,"description":"","link":"https:\/\/www.yunrui-controls.com\/th\/brands\/honeywell\/temperature-transmitters-honeywell\/","name":"\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e2d\u0e38\u0e13\u0e2b\u0e20\u0e39\u0e21\u0e34","slug":"temperature-transmitters-honeywell","taxonomy":"brands","parent":116,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v26.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Temperature Transmitters - YunRui<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yunrui-controls.com\/th\/brands\/honeywell\/temperature-transmitters-honeywell\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Temperature Transmitters Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yunrui-controls.com\/th\/brands\/honeywell\/temperature-transmitters-honeywell\/\" \/>\n<meta property=\"og:site_name\" content=\"Fisher, E+H &amp; Rosemount Supplier from China | 100% Original | YUNRUI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/temperature-transmitters-honeywell\/\",\"url\":\"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/temperature-transmitters-honeywell\/\",\"name\":\"Temperature Transmitters - YunRui\",\"isPartOf\":{\"@id\":\"https:\/\/www.yunrui-controls.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/temperature-transmitters-honeywell\/#breadcrumb\"},\"inLanguage\":\"th\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/temperature-transmitters-honeywell\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.yunrui-controls.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HoneyWell\",\"item\":\"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Temperature Transmitters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.yunrui-controls.com\/#website\",\"url\":\"https:\/\/www.yunrui-controls.com\/\",\"name\":\"Process Instrument & Valve Supplier from China | YUNRUI\",\"description\":\"YUNRUI is your trusted authorized distributor and stockist in China for original Fisher valves, E+H, and Rosemount instruments. Fast Middle East delivery. Get a quote!\",\"publisher\":{\"@id\":\"https:\/\/www.yunrui-controls.com\/#organization\"},\"alternateName\":\"YRCONTROLS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.yunrui-controls.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.yunrui-controls.com\/#organization\",\"name\":\"YUNRUI\",\"alternateName\":\"YUNRUI TRADING\",\"url\":\"https:\/\/www.yunrui-controls.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.yunrui-controls.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.yunrui-controls.com\/wp-content\/uploads\/2026\/03\/original-yunrui-logo-from-china-supplier-yunrui.png\",\"contentUrl\":\"https:\/\/www.yunrui-controls.com\/wp-content\/uploads\/2026\/03\/original-yunrui-logo-from-china-supplier-yunrui.png\",\"width\":512,\"height\":512,\"caption\":\"YUNRUI\"},\"image\":{\"@id\":\"https:\/\/www.yunrui-controls.com\/#\/schema\/logo\/image\/\"},\"telephone\":\"8618710784030\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Temperature Transmitters - YunRui","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yunrui-controls.com\/th\/brands\/honeywell\/temperature-transmitters-honeywell\/","og_locale":"th_TH","og_type":"article","og_title":"Temperature Transmitters Archives","og_url":"https:\/\/www.yunrui-controls.com\/th\/brands\/honeywell\/temperature-transmitters-honeywell\/","og_site_name":"Fisher, E+H &amp; Rosemount Supplier from China | 100% Original | YUNRUI","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/temperature-transmitters-honeywell\/","url":"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/temperature-transmitters-honeywell\/","name":"Temperature Transmitters - YunRui","isPartOf":{"@id":"https:\/\/www.yunrui-controls.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/temperature-transmitters-honeywell\/#breadcrumb"},"inLanguage":"th"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/temperature-transmitters-honeywell\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.yunrui-controls.com\/"},{"@type":"ListItem","position":2,"name":"HoneyWell","item":"https:\/\/www.yunrui-controls.com\/brands\/honeywell\/"},{"@type":"ListItem","position":3,"name":"Temperature Transmitters"}]},{"@type":"WebSite","@id":"https:\/\/www.yunrui-controls.com\/#website","url":"https:\/\/www.yunrui-controls.com\/","name":"\u0e1c\u0e39\u0e49\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e27\u0e31\u0e14\u0e41\u0e25\u0e30\u0e27\u0e32\u0e25\u0e4c\u0e27\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 | YUNRUI","description":"YUNRUI \u0e04\u0e37\u0e2d\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d\u0e44\u0e14\u0e49\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e08\u0e35\u0e19 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e27\u0e32\u0e25\u0e4c\u0e27 Fisher \u0e41\u0e17\u0e49, \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d E+H \u0e41\u0e25\u0e30 Rosemount \u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\u0e23\u0e27\u0e14\u0e40\u0e23\u0e47\u0e27\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e01\u0e25\u0e32\u0e07 \u0e02\u0e2d\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22!","publisher":{"@id":"https:\/\/www.yunrui-controls.com\/#organization"},"alternateName":"YRCONTROLS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yunrui-controls.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.yunrui-controls.com\/#organization","name":"\u0e2b\u0e22\u0e38\u0e19\u0e23\u0e38\u0e22","alternateName":"YUNRUI TRADING","url":"https:\/\/www.yunrui-controls.com\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.yunrui-controls.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.yunrui-controls.com\/wp-content\/uploads\/2026\/03\/original-yunrui-logo-from-china-supplier-yunrui.png","contentUrl":"https:\/\/www.yunrui-controls.com\/wp-content\/uploads\/2026\/03\/original-yunrui-logo-from-china-supplier-yunrui.png","width":512,"height":512,"caption":"YUNRUI"},"image":{"@id":"https:\/\/www.yunrui-controls.com\/#\/schema\/logo\/image\/"},"telephone":"8618710784030"}]}},"_links":{"self":[{"href":"https:\/\/www.yunrui-controls.com\/th\/wp-json\/wp\/v2\/brands\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yunrui-controls.com\/th\/wp-json\/wp\/v2\/brands"}],"about":[{"href":"https:\/\/www.yunrui-controls.com\/th\/wp-json\/wp\/v2\/taxonomies\/brands"}],"up":[{"embeddable":true,"href":"https:\/\/www.yunrui-controls.com\/th\/wp-json\/wp\/v2\/brands\/116"}],"wp:post_type":[{"href":"https:\/\/www.yunrui-controls.com\/th\/wp-json\/wp\/v2\/products?brands=360"}],"curies":[{"name":"\u0e14\u0e31\u0e1a\u0e40\u0e1a\u0e34\u0e25\u0e22\u0e39\u0e1e\u0e35","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}